{"id":25991,"count":9,"description":"","link":"https:\/\/yoyaku.io\/es\/label\/bloop-recordings\/","name":"Grabaciones Bloop","slug":"bloop-recordings","taxonomy":"musiclabel","meta":{"label_discogs_id":60215,"label_discogs_url":"https:\/\/www.discogs.com\/label\/60215-bloop-recordings","label_image_id":636557,"label_profile":"Lisbon based electronic music label run by Cruz","label_country":"Portugal","label_founded_year":0,"label_website":"http:\/\/www.myspace.com\/blooprecordings","label_instagram":"","label_facebook":"https:\/\/www.facebook.com\/blooprecordings\/","label_bandcamp":"","label_soundcloud":"https:\/\/soundcloud.com\/blooprecordings","label_youtube":"","musiclabel_logo_url":"","musiclabel_bio_curated":"","musiclabel_instagram_curated":"","musiclabel_website_curated":"","musiclabel_discogs_url_curated":""},"default_distributor":{"term_id":14622,"name":"carpet","slug":"carpet"},"_links":{"self":[{"href":"https:\/\/yoyaku.io\/es\/wp-json\/wp\/v2\/musiclabel\/25991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yoyaku.io\/es\/wp-json\/wp\/v2\/musiclabel"}],"about":[{"href":"https:\/\/yoyaku.io\/es\/wp-json\/wp\/v2\/taxonomies\/musiclabel"}],"wp:post_type":[{"href":"https:\/\/yoyaku.io\/es\/wp-json\/wp\/v2\/product?musiclabel=25991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}